{"id":6939,"date":"2022-11-13T12:07:33","date_gmt":"2022-11-13T11:07:33","guid":{"rendered":"https:\/\/www.loop4live.com\/?page_id=6939"},"modified":"2022-11-13T15:55:43","modified_gmt":"2022-11-13T14:55:43","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.loop4live.com\/de\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div class=\"l4l_page_padding\">\n<h2>Privacy Policy<\/h2>\n<p>Loop4live verpflichtet sich, Ihre Privatsph\u00e4re zu sch\u00fctzen. Wenden Sie sich an <a href=\"mailto:contact@loop4live.com\">contact@loop4live.com<\/a>, wenn Sie Fragen oder Probleme bez\u00fcglich der Verwendung Ihrer<\/p>\n<p>Durch die Nutzung dieser Website und\/oder unserer Dienstleistungen erkl\u00e4ren Sie sich mit der in dieser Datenschutzrichtlinie beschriebenen Verarbeitung Ihrer pers\u00f6nlichen Daten einverstanden.<br \/>\nDiese Datenschutzrichtlinie ist Teil unserer Allgemeinen Gesch\u00e4ftsbedingungen; durch Ihre Zustimmung zu den Allgemeinen Gesch\u00e4ftsbedingungen erkl\u00e4ren Sie sich auch mit dieser Richtlinie einverstanden. Im Falle einer Kollision von Begriffen, die in den Allgemeinen Gesch\u00e4ftsbedingungen und der Datenschutzrichtlinie verwendet werden, hat letztere Vorrang.<\/p>\n<h3>Inhalts\u00fcbersicht<\/h3>\n<ol>\n<li><a href=\"#gdpr-definitions\">In dieser Politik verwendete Definitionen<\/a><\/li>\n<li><a href=\"#gdpr-principles\">Befolgte Datenschutzgrunds\u00e4tze<\/a><\/li>\n<li><a href=\"#gdpr-rights\">Welche Rechte haben Sie in Bezug auf Ihre pers\u00f6nlichen Daten?<\/a><\/li>\n<li><a href=\"#gdpr-information\">Welche pers\u00f6nlichen Daten wir \u00fcber Sie sammeln<\/a><\/li>\n<li><a href=\"#gdpr-processing\">Wie wir Ihre pers\u00f6nlichen Daten verwenden<\/a><\/li>\n<li><a href=\"#gdpr-sharing\">Wer sonst noch Zugang zu Ihren pers\u00f6nlichen Daten hat<\/a><\/li>\n<li><a href=\"#gdpr-security\">Wie wir Ihre Daten sch\u00fctzen<\/a><\/li>\n<li><a href=\"#gdpr-cookies\">Informationen \u00fcber Cookies<\/a><\/li>\n<li><a href=\"#gdpr-contact\">Kontaktinformationen<\/a><\/li>\n<\/ol>\n<h3 id=\"gdpr-definitions\">Definitionen<\/h3>\n<p><strong>Pers\u00f6nliche Daten<\/strong>\u00a0\u2013 alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person beziehen.<br \/>\n<strong>Verarbeitung<\/strong>\u00a0\u2013 jeder Vorgang oder jede Reihe von Vorg\u00e4ngen, die an personenbezogenen Daten oder an Gruppen von personenbezogenen Daten durchgef\u00fchrt werden.<br \/>\n<strong>Gegenstand der Daten<\/strong>\u00a0&#8211; eine nat\u00fcrliche Person, deren personenbezogene Daten verarbeitet werden.<br \/>\n<strong>Kind<\/strong> &#8211;\u00a0eine nat\u00fcrliche Person unter 16 Jahren.<br \/>\n<strong>Wir\/uns<\/strong> (entweder gro\u00dfgeschrieben oder nicht)\u00a0\u2013 Loop4live<\/p>\n<h3 id=\"gdpr-principles\">Grunds\u00e4tze des Datenschutzes<\/h3>\n<p>Wir verpflichten uns zur Einhaltung der folgenden Datenschutzgrunds\u00e4tze:<\/p>\n<ul>\n<li>Die Verarbeitung ist rechtm\u00e4\u00dfig, fair und transparent. Unsere Verarbeitungst\u00e4tigkeiten haben rechtm\u00e4\u00dfige Gr\u00fcnde. Wir ber\u00fccksichtigen stets Ihre Rechte, bevor wir personenbezogene Daten verarbeiten. Wir werden Ihnen auf Anfrage Informationen \u00fcber die Verarbeitung zur Verf\u00fcgung stellen.<\/li>\n<li>Die Verarbeitung ist auf den Zweck beschr\u00e4nkt. Unsere Verarbeitungst\u00e4tigkeiten entsprechen dem Zweck, f\u00fcr den die personenbezogenen Daten erhoben wurden.<\/li>\n<li>Die Verarbeitung erfolgt mit einem Minimum an Daten. Wir sammeln und verarbeiten nur die minimale Menge an personenbezogenen Daten, die f\u00fcr den jeweiligen Zweck erforderlich ist.<\/li>\n<li>Die Verarbeitung ist auf einen bestimmten Zeitraum beschr\u00e4nkt. Wir werden Ihre personenbezogenen Daten nicht l\u00e4nger als n\u00f6tig speichern.<\/li>\n<li>Wir werden unser Bestes tun, um die Richtigkeit der Daten zu gew\u00e4hrleisten.<\/li>\n<li>Wir werden unser Bestes tun, um die Integrit\u00e4t und Vertraulichkeit der Daten zu gew\u00e4hrleisten.<\/li>\n<\/ul>\n<h3 id=\"gdpr-rights\">Die Rechte der betroffenen Person<\/h3>\n<p>Die betroffene Person hat die folgenden Rechte:<\/p>\n<ol>\n<li>Recht auf Information &#8211; das hei\u00dft, Sie haben das Recht zu erfahren, ob Ihre personenbezogenen Daten verarbeitet werden, welche Daten gesammelt werden, woher sie stammen und warum und von wem sie verarbeitet werden.<\/li>\n<li>Recht auf Zugang &#8211; das hei\u00dft, Sie haben das Recht auf Zugang zu den Daten, die von\/\u00fcber Sie gesammelt wurden. Dazu geh\u00f6rt auch das Recht, eine Kopie der \u00fcber Sie erhobenen personenbezogenen Daten anzufordern und zu erhalten.<\/li>\n<li>Recht auf Berichtigung &#8211; das hei\u00dft, Sie haben das Recht, die Berichtigung oder L\u00f6schung Ihrer personenbezogenen Daten zu verlangen, wenn diese unrichtig oder unvollst\u00e4ndig sind.<\/li>\n<li>Recht auf L\u00f6schung &#8211; das bedeutet, dass Sie unter bestimmten Umst\u00e4nden verlangen k\u00f6nnen, dass Ihre personenbezogenen Daten aus unseren Unterlagen gel\u00f6scht werden.<\/li>\n<li>Recht auf Einschr\u00e4nkung der Verarbeitung &#8211; d. h. unter bestimmten Bedingungen haben Sie das Recht, die Verarbeitung Ihrer personenbezogenen Daten einzuschr\u00e4nken.<\/li>\n<li>Recht auf Widerspruch gegen die Verarbeitung &#8211; das bedeutet, dass Sie in bestimmten F\u00e4llen das Recht haben, der Verarbeitung Ihrer personenbezogenen Daten zu widersprechen, zum Beispiel im Falle von Direktmarketing.<\/li>\n<li>Recht auf Widerspruch gegen die automatisierte Verarbeitung &#8211; d. h. Sie haben das Recht, der automatisierten Verarbeitung, einschlie\u00dflich Profiling, zu widersprechen und nicht einer Entscheidung unterworfen zu werden, die ausschlie\u00dflich auf einer automatisierten Verarbeitung beruht. Dieses Recht k\u00f6nnen Sie immer dann aus\u00fcben, wenn das Ergebnis des Profilings rechtliche Auswirkungen hat, die Sie betreffen oder erheblich beeintr\u00e4chtigen.<\/li>\n<li>Recht auf Daten\u00fcbertragbarkeit &#8211; Sie haben das Recht, Ihre personenbezogenen Daten in einem maschinenlesbaren Format oder, falls dies m\u00f6glich ist, als direkte \u00dcbertragung von einem Auftragsverarbeiter zu einem anderen zu erhalten.<\/li>\n<li>Recht auf Beschwerde &#8211; falls wir Ihre Anfrage im Rahmen des Auskunftsrechts ablehnen, werden wir Ihnen die Gr\u00fcnde daf\u00fcr mitteilen. Wenn Sie mit der Art und Weise, wie Ihr Antrag bearbeitet wurde, nicht zufrieden sind, wenden Sie sich bitte an uns.<\/li>\n<li>Recht auf Unterst\u00fctzung durch eine Aufsichtsbeh\u00f6rde &#8211; Sie haben das Recht auf Unterst\u00fctzung durch eine Aufsichtsbeh\u00f6rde und das Recht auf andere Rechtsbehelfe, wie z. B. die Geltendmachung von Schadensersatz.<\/li>\n<li>Recht auf Widerruf der Einwilligung &#8211; Sie haben das Recht, eine erteilte Einwilligung zur Verarbeitung Ihrer personenbezogenen Daten zu widerrufen.<\/li>\n<li>Ein Tool zur Verwaltung Ihrer personenbezogenen Daten steht Ihnen unter folgender Adresse zur Verf\u00fcgung: <a href=\"https:\/\/www.loop4live.com\/privacy-tools\/\">privacy tools<\/a><\/li>\n<\/ol>\n<h3 id=\"gdpr-information\">Daten, die wir sammeln<\/h3>\n<p><strong>Informationen, die Sie uns zur Verf\u00fcgung gestellt haben<\/strong><br \/>\nDabei kann es sich um Ihre E-Mail-Adresse, Ihren Namen, Ihre Rechnungsanschrift, Ihre Wohnanschrift usw. handeln &#8211; haupts\u00e4chlich um Informationen, die erforderlich sind, um Ihnen ein Produkt\/eine Dienstleistung zu liefern oder um Ihre Kundenerfahrung mit uns zu verbessern. Wir speichern die Informationen, die Sie uns zur Verf\u00fcgung stellen, damit Sie Kommentare abgeben oder andere Aktivit\u00e4ten auf der Website durchf\u00fchren k\u00f6nnen. Zu diesen Informationen geh\u00f6ren beispielsweise Ihr Name und Ihre E-Mail-Adresse.<\/p>\n<p><strong>Automatisch erfasste Informationen \u00fcber Sie<\/strong><br \/>\nDazu geh\u00f6ren Informationen, die automatisch von Cookies und anderen Sitzungsprogrammen gespeichert werden. Zum Beispiel Informationen \u00fcber Ihren Einkaufswagen, Ihre IP-Adresse, Ihre Einkaufshistorie (falls vorhanden) usw. Diese Informationen werden verwendet, um Ihr Kundenerlebnis zu verbessern. Wenn Sie unsere Dienste nutzen oder sich die Inhalte unserer Website ansehen, k\u00f6nnen Ihre Aktivit\u00e4ten protokolliert werden.<\/p>\n<p><strong>\u00d6ffentlich zug\u00e4ngliche Informationen<\/strong><br \/>\nWir k\u00f6nnen Informationen \u00fcber Sie sammeln, die \u00f6ffentlich zug\u00e4nglich sind.<\/p>\n<h3 id=\"gdpr-processing\">Wie wir Ihre pers\u00f6nlichen Daten verwenden<\/h3>\n<p>Wir verwenden Ihre pers\u00f6nlichen Daten, um::<\/p>\n<ul>\n<li>unsere Dienstleistungen f\u00fcr Sie zu erbringen. Dazu geh\u00f6ren zum Beispiel die Registrierung Ihres Kontos, die Bereitstellung anderer Produkte und Dienstleistungen, die Sie angefordert haben, die Bereitstellung von Werbeartikeln auf Ihren Wunsch hin und die Kommunikation mit Ihnen in Bezug auf diese Produkte und Dienstleistungen, die Kommunikation und Interaktion mit Ihnen und die Benachrichtigung \u00fcber \u00c4nderungen an Dienstleistungen.<\/li>\n<li>Ihr Kundenerlebnis zu verbessern;<\/li>\n<li>eine gesetzliche oder vertragliche Verpflichtung zu erf\u00fcllen;<\/li>\n<\/ul>\n<p>Wir verwenden Ihre personenbezogenen Daten aus legitimen Gr\u00fcnden und\/oder mit Ihrer Zustimmung.<\/p>\n<p>Aufgrund des Abschlusses eines Vertrags oder der Erf\u00fcllung vertraglicher Verpflichtungen verarbeiten wir Ihre personenbezogenen Daten f\u00fcr die folgenden Zwecke:<\/p>\n<ul>\n<li>um Sie zu identifizieren;<\/li>\n<li>um Ihnen eine Dienstleistung zu erbringen oder um Ihnen ein Produkt zu senden\/anzubieten;<\/li>\n<li>entweder f\u00fcr den Verkauf oder die Rechnungsstellung zu kommunizieren;<\/li>\n<\/ul>\n<p>Auf der Grundlage eines berechtigten Interesses verarbeiten wir Ihre personenbezogenen Daten f\u00fcr die folgenden Zwecke:<\/p>\n<ul>\n<li>um Ihnen personalisierte Angebote* (von uns und\/oder unseren sorgf\u00e4ltig ausgew\u00e4hlten Partnern) zu senden;<\/li>\n<li>zur Verwaltung und Analyse unseres Kundenstamms (Kaufverhalten und -historie), um die Qualit\u00e4t, Vielfalt und Verf\u00fcgbarkeit der angebotenen Produkte\/Dienstleistungen zu verbessern;<\/li>\n<li>eine Frage zur Kundenzufriedenheit zu stellen;;<\/li>\n<\/ul>\n<p>Solange Sie uns nicht anderweitig informiert haben, betrachten wir es als unser berechtigtes Interesse, Ihnen Produkte\/Dienstleistungen anzubieten, die Ihrem Kauf-\/Browsing-Verhalten \u00e4hnlich oder gleich sind.<\/p>\n<p>Mit Ihrer Zustimmung verarbeiten wir Ihre personenbezogenen Daten f\u00fcr die folgenden Zwecke:<\/p>\n<ul>\n<li>um Ihnen Newsletter und Aktionsangebote (von uns und\/oder unseren sorgf\u00e4ltig ausgew\u00e4hlten Partnern) zuzusenden;<\/li>\n<li>f\u00fcr andere Zwecke, f\u00fcr die wir Ihre Zustimmung eingeholt haben;<\/li>\n<\/ul>\n<p>Wir verarbeiten Ihre pers\u00f6nlichen Daten, um die aus dem Gesetz erwachsenden Verpflichtungen zu erf\u00fcllen und\/oder Ihre pers\u00f6nlichen Daten f\u00fcr die vom Gesetz vorgesehenen M\u00f6glichkeiten zu nutzen. Wir behalten uns das Recht vor, gesammelte personenbezogene Daten zu anonymisieren und solche Daten zu verwenden. Wir werden Daten au\u00dferhalb des Geltungsbereichs dieser Richtlinie nur verwenden, wenn sie anonymisiert sind. Wir speichern Ihre Rechnungsdaten und andere \u00fcber Sie gesammelte Informationen so lange, wie es f\u00fcr Buchhaltungszwecke oder andere sich aus dem Gesetz ergebende Verpflichtungen erforderlich ist, jedoch nicht l\u00e4nger als . <strong>2 Jahre.<br \/>\n<\/strong><\/p>\n<p>Es kann sein, dass wir Ihre personenbezogenen Daten f\u00fcr weitere Zwecke verarbeiten, die hier nicht genannt sind, die aber mit dem urspr\u00fcnglichen Zweck, f\u00fcr den die Daten erhoben wurden, vereinbar sind. Um dies zu tun, werden wir sicherstellen, dass:<\/p>\n<ul>\n<li>die Verbindung zwischen Zweck, Kontext und Art der personenbezogenen Daten f\u00fcr die weitere Verarbeitung geeignet ist;<\/li>\n<li>die weitere Verarbeitung Ihre Interessen nicht beeintr\u00e4chtigen w\u00fcrde;<\/li>\n<li>die Verarbeitung angemessen gesch\u00fctzt ist.<\/li>\n<\/ul>\n<p>Wir werden Sie \u00fcber jede weitere Verarbeitung und jeden weiteren Zweck informieren.<\/p>\n<h2>Wer in unserem Team hat Zugang<\/h2>\n<p>Die Mitglieder unseres Teams haben Zugang zu den Informationen, die Sie uns zur Verf\u00fcgung stellen. Zum Beispiel k\u00f6nnen sowohl Administratoren als auch Shop-Manager darauf zugreifen:<\/p>\n<ul>\n<li>Bestellinformationen, z. B. was gekauft wurde, wann es gekauft wurde und wohin es geschickt werden soll, und<\/li>\n<li>Kundeninformationen wie Ihr Name, Ihre E-Mail-Adresse sowie Rechnungs- und Versandinformationen.<\/li>\n<\/ul>\n<p>Unsere Teammitglieder haben Zugriff auf diese Informationen, um Bestellungen auszuf\u00fchren, R\u00fcckerstattungen zu bearbeiten und Sie zu unterst\u00fctzen.<\/p>\n<h3 id=\"gdpr-sharing\">Wer kann sonst noch auf Ihre pers\u00f6nlichen Daten zugreifen?<\/h3>\n<p>Wir geben Ihre pers\u00f6nlichen Daten nicht an Fremde weiter. Pers\u00f6nliche Daten \u00fcber Sie werden in einigen F\u00e4llen an unsere vertrauensw\u00fcrdigen Partner weitergegeben, um entweder die Bereitstellung des Dienstes f\u00fcr Sie zu erm\u00f6glichen oder um Ihre Kundenerfahrung zu verbessern. Wir teilen Ihre Daten mit:<\/p>\n<p>Wir arbeiten nur mit Verarbeitungspartnern zusammen, die in der Lage sind, ein angemessenes Schutzniveau f\u00fcr Ihre personenbezogenen Daten zu gew\u00e4hrleisten. Wir geben Ihre personenbezogenen Daten an Dritte oder Beh\u00f6rden weiter, wenn wir dazu gesetzlich verpflichtet sind. Wir k\u00f6nnen Ihre personenbezogenen Daten an Dritte weitergeben, wenn Sie dem zugestimmt haben oder wenn es andere rechtliche Gr\u00fcnde daf\u00fcr gibt.<\/p>\n<p><strong>Unsere Verarbeitungspartner:<\/strong><\/p>\n<ul>\n<li>Google captcha : um zu \u00fcberpr\u00fcfen, dass Sie kein Roboter sind<\/li>\n<li>Bezahlungen: Wir akzeptieren Zahlungen \u00fcber PayPal. Bei der Zahlungsabwicklung werden einige Ihrer Daten an PayPal weitergegeben, darunter auch Informationen, die f\u00fcr die Bearbeitung oder Unterst\u00fctzung der Zahlung erforderlich sind, wie z. B. die Kaufsumme und die Rechnungsdaten. Weitere Informationen finden Sie in den Datenschutzbestimmungen von PayPal.<\/li>\n<\/ul>\n<h3 id=\"gdpr-security\">Wie wir Ihre Daten sch\u00fctzen<\/h3>\n<p>Wir tun unser Bestes, um Ihre pers\u00f6nlichen Daten sicher zu halten. Wir verwenden sichere Protokolle f\u00fcr die Kommunikation und die \u00dcbertragung von Daten (z. B. HTTPS). Wir verwenden Anonymisierungs- und Pseudonymisierungsverfahren, wo dies angemessen ist. Wir \u00fcberwachen unsere Systeme auf m\u00f6gliche Schwachstellen und Angriffe.<\/p>\n<p>Auch wenn wir unser Bestes tun, k\u00f6nnen wir die Sicherheit von Informationen nicht garantieren. Wir versprechen jedoch, die zust\u00e4ndigen Beh\u00f6rden \u00fcber Datenschutzverletzungen zu informieren. Wir werden Sie auch benachrichtigen, wenn eine Bedrohung Ihrer Rechte oder Interessen vorliegt. Wir werden alles tun, was wir vern\u00fcnftigerweise tun k\u00f6nnen, um Sicherheitsverletzungen zu verhindern und die Beh\u00f6rden zu unterst\u00fctzen, falls es zu Verletzungen kommt.<\/p>\n<p>Wenn Sie ein Konto bei uns haben, beachten Sie bitte, dass Sie Ihren Benutzernamen und Ihr Passwort geheim halten m\u00fcssen.<\/p>\n<h3>Kind<\/h3>\n<p>Wir haben nicht die Absicht, wissentlich Informationen von Kindern zu sammeln oder zu erfassen. Wir richten uns mit unseren Diensten nicht an Kinder.<\/p>\n<h3 id=\"gdpr-cookies\">Cookies und andere von uns verwendete Technologien<\/h3>\n<p>Wir verwenden Cookies und\/oder \u00e4hnliche Technologien, um das Kundenverhalten zu analysieren, die Website zu verwalten, die Bewegungen der Nutzer zu verfolgen und Informationen \u00fcber die Nutzer zu sammeln. Dies geschieht, um Ihre Erfahrung mit uns zu personalisieren und zu verbessern.<\/p>\n<p>Ein Cookie ist eine kleine Textdatei, die auf Ihrem Computer gespeichert wird. In Cookies werden Informationen gespeichert, die f\u00fcr das Funktionieren von Websites erforderlich sind. Nur wir k\u00f6nnen auf die von unserer Website erstellten Cookies zugreifen. Sie k\u00f6nnen Ihre Cookies auf Browser-Ebene kontrollieren. Wenn Sie sich daf\u00fcr entscheiden, Cookies zu deaktivieren, kann die Nutzung bestimmter Funktionen beeintr\u00e4chtigt werden.<\/p>\n<p>Wir verwenden Cookies f\u00fcr die folgenden Zwecke:<\/p>\n<ul>\n<li>Notwendige Cookies &#8211; diese Cookies sind erforderlich, damit Sie einige wichtige Funktionen unserer Website nutzen k\u00f6nnen, z. B. das Einloggen. Diese Cookies sammeln keine pers\u00f6nlichen Informationen.<\/li>\n<li>Funktionalit\u00e4ts-Cookies &#8211; diese Cookies bieten Funktionen, die die Nutzung unseres Dienstes bequemer machen und die Bereitstellung personalisierter Funktionen erm\u00f6glichen. Zum Beispiel k\u00f6nnen sie sich Ihren Namen und Ihre E-Mail-Adresse in Kommentarformularen merken, damit Sie diese Informationen beim n\u00e4chsten Mal nicht erneut eingeben m\u00fcssen, wenn Sie kommentieren.<\/li>\n<li>Analytics-Cookies &#8211; diese Cookies werden verwendet, um die Nutzung und Leistung unserer Website und Dienstleistungen zu verfolgen<\/li>\n<li>Werbe-Cookies &#8211; diese Cookies werden verwendet, um Ihnen Werbung zu liefern, die f\u00fcr Sie und Ihre Interessen relevant ist. Au\u00dferdem werden sie verwendet, um die Anzahl der Anzeigen zu begrenzen, die Sie sehen. Sie werden in der Regel von Werbenetzwerken mit der Erlaubnis des Website-Betreibers auf der Website platziert. Diese Cookies merken sich, dass Sie eine Website besucht haben, und diese Informationen werden an andere Organisationen wie z. B. Werbetreibende weitergegeben. H\u00e4ufig sind Targeting- oder Werbe-Cookies mit Website-Funktionen verbunden, die von der anderen Organisation bereitgestellt werden.<\/li>\n<\/ul>\n<p>https:\/\/www.loop4live.com\/wp-admin\/options-general.php<br \/>\nSie k\u00f6nnen die auf Ihrem Computer gespeicherten Cookies \u00fcber Ihre Browsereinstellungen entfernen. Alternativ k\u00f6nnen Sie einige Cookies von Drittanbietern kontrollieren, indem Sie eine Plattform zur Verbesserung der Privatsph\u00e4re wie <a href=\"http:\/\/optout.aboutads.info\/#!\/\" target=\"_blank\" rel=\"noopener noreferrer\">optout.aboutads.info<\/a> oder <a href=\"http:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">youronlinechoices.com<\/a> nutzen. Weitere Informationen \u00fcber Cookies finden Sie unter  <a href=\"http:\/\/www.allaboutcookies.org\" target=\"_blank\" rel=\"noopener noreferrer\">allaboutcookies.org<\/a> .<\/p>\n<p>Wir verwenden Google Analytics, um den Verkehr auf unserer Website zu messen.  Google hat seine eigenen Datenschutzbestimmungen, die Sie <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a>einsehen k\u00f6nnen. Wenn Sie das Tracking durch Google Analytics deaktivieren m\u00f6chten, besuchen Sie die Seite zur <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noopener noreferrer\">Deaktivierung von Google Analyticsoogle Analytics opt-out page<\/a>.<\/p>\n<h3 id=\"gdpr-contact\">Wie Sie Ihre Daten l\u00f6schen k\u00f6nnen:<\/h3>\n<p>Wir stellen Ihnen in der Fu\u00dfzeile dieser Website ein Tool zur Verf\u00fcgung, mit dem Sie Ihre pers\u00f6nlichen Daten abrufen oder l\u00f6schen k\u00f6nnen. Sie m\u00fcssen dazu angemeldet sein.<\/p>\n<h3><\/h3>\n<h3 id=\"gdpr-contact\">Kontaktinformationen<\/h3>\n<p><strong id=\"gdpr-dpa\">Aufsichtsbeh\u00f6rde<\/strong><br \/>\nWebsite: <a href=\"http:\/\/www.cnil.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.cnil.fr\/<\/a><br \/>\nTelefon: +33 1 53 73 22 22<\/p>\n<h3 id=\"gdpr-changes\">\u00c4nderungen an dieser Datenschutzrichtlinie<\/h3>\n<p>Wir behalten uns das Recht vor, diese Datenschutzrichtlinie zu \u00e4ndern.<br \/>\nDie letzte \u00c4nderung wurde am 25. M\u00e4rz 2020 vorgenommen.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Loop4live verpflichtet sich, Ihre Privatsph\u00e4re zu sch\u00fctzen. Wenden Sie sich an contact@loop4live.com, wenn Sie Fragen oder Probleme bez\u00fcglich der Verwendung Ihrer Durch die Nutzung dieser Website und\/oder unserer Dienstleistungen erkl\u00e4ren Sie sich mit der in dieser Datenschutzrichtlinie beschriebenen Verarbeitung Ihrer pers\u00f6nlichen Daten einverstanden. Diese Datenschutzrichtlinie ist Teil unserer Allgemeinen Gesch\u00e4ftsbedingungen; durch Ihre Zustimmung [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-6939","page","type-page","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Loop4Live<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Loop4Live\" \/>\n<meta property=\"og:description\" content=\"Privacy Policy Loop4live verpflichtet sich, Ihre Privatsph\u00e4re zu sch\u00fctzen. Wenden Sie sich an contact@loop4live.com, wenn Sie Fragen oder Probleme bez\u00fcglich der Verwendung Ihrer Durch die Nutzung dieser Website und\/oder unserer Dienstleistungen erkl\u00e4ren Sie sich mit der in dieser Datenschutzrichtlinie beschriebenen Verarbeitung Ihrer pers\u00f6nlichen Daten einverstanden. Diese Datenschutzrichtlinie ist Teil unserer Allgemeinen Gesch\u00e4ftsbedingungen; durch Ihre Zustimmung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.loop4live.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Loop4Live\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Loop4live-101444891316828\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-13T14:55:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Loop4Live\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#website\"},\"datePublished\":\"2022-11-13T11:07:33+00:00\",\"dateModified\":\"2022-11-13T14:55:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.loop4live.com\\\/de\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/\",\"name\":\"Loop4Live\",\"description\":\"Ableton Live foot controller\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#organization\",\"name\":\"Loop4Live\",\"url\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.loop4live.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/LOOP4live_logo_1080p.png\",\"contentUrl\":\"https:\\\/\\\/www.loop4live.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/LOOP4live_logo_1080p.png\",\"width\":1072,\"height\":419,\"caption\":\"Loop4Live\"},\"image\":{\"@id\":\"https:\\\/\\\/www.loop4live.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Loop4live-101444891316828\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyOGPjEe4G_PM1z74w4PSdw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Loop4Live","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Privacy Policy - Loop4Live","og_description":"Privacy Policy Loop4live verpflichtet sich, Ihre Privatsph\u00e4re zu sch\u00fctzen. Wenden Sie sich an contact@loop4live.com, wenn Sie Fragen oder Probleme bez\u00fcglich der Verwendung Ihrer Durch die Nutzung dieser Website und\/oder unserer Dienstleistungen erkl\u00e4ren Sie sich mit der in dieser Datenschutzrichtlinie beschriebenen Verarbeitung Ihrer pers\u00f6nlichen Daten einverstanden. Diese Datenschutzrichtlinie ist Teil unserer Allgemeinen Gesch\u00e4ftsbedingungen; durch Ihre Zustimmung [&hellip;]","og_url":"https:\/\/www.loop4live.com\/de\/privacy-policy\/","og_site_name":"Loop4Live","article_publisher":"https:\/\/www.facebook.com\/Loop4live-101444891316828","article_modified_time":"2022-11-13T14:55:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.loop4live.com\/de\/privacy-policy\/","url":"https:\/\/www.loop4live.com\/de\/privacy-policy\/","name":"Privacy Policy - Loop4Live","isPartOf":{"@id":"https:\/\/www.loop4live.com\/de\/#website"},"datePublished":"2022-11-13T11:07:33+00:00","dateModified":"2022-11-13T14:55:43+00:00","breadcrumb":{"@id":"https:\/\/www.loop4live.com\/de\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.loop4live.com\/de\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.loop4live.com\/de\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.loop4live.com\/de\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.loop4live.com\/de\/#website","url":"https:\/\/www.loop4live.com\/de\/","name":"Loop4Live","description":"Ableton Live foot controller","publisher":{"@id":"https:\/\/www.loop4live.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.loop4live.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.loop4live.com\/de\/#organization","name":"Loop4Live","url":"https:\/\/www.loop4live.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.loop4live.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.loop4live.com\/wp-content\/uploads\/2020\/04\/LOOP4live_logo_1080p.png","contentUrl":"https:\/\/www.loop4live.com\/wp-content\/uploads\/2020\/04\/LOOP4live_logo_1080p.png","width":1072,"height":419,"caption":"Loop4Live"},"image":{"@id":"https:\/\/www.loop4live.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Loop4live-101444891316828","https:\/\/www.youtube.com\/channel\/UCyOGPjEe4G_PM1z74w4PSdw"]}]}},"_links":{"self":[{"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/pages\/6939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/comments?post=6939"}],"version-history":[{"count":4,"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/pages\/6939\/revisions"}],"predecessor-version":[{"id":7016,"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/pages\/6939\/revisions\/7016"}],"wp:attachment":[{"href":"https:\/\/www.loop4live.com\/de\/wp-json\/wp\/v2\/media?parent=6939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}